{"id":60883,"date":"2020-10-23T13:03:27","date_gmt":"2020-10-23T17:03:27","guid":{"rendered":"https:\/\/dev-cglcc-multisite.pantheonsite.io\/fr\/news\/small-business-month-presented-by-td-eac-construction\/"},"modified":"2025-10-22T15:58:17","modified_gmt":"2025-10-22T19:58:17","slug":"mois-de-la-pme-presente-par-td-eac-construction","status":"publish","type":"post","link":"https:\/\/queerchamber.ca\/fr\/news\/mois-de-la-pme-presente-par-td-eac-construction\/","title":{"rendered":"Le Mois de la PME pr\u00e9sent\u00e9 par la TD : EAC Construction"},"content":{"rendered":"\n<p>Octobre est le Mois de la PME, et en collaboration avec <a href=\"https:\/\/www.td.com\/ca\/en\/personal-banking\/\">la TD<\/a> , nous dressons le profil des petites entreprises appartenant \u00e0 des personnes 2ELGBTQI+ partout au Canada qui ont r\u00e9ussi \u00e0 traverser la pand\u00e9mie de COVID-19.<\/p>\n\n\n\n<p>Nous discuterons de la fa\u00e7on dont ils ont r\u00e9ussi, de certains des d\u00e9fis auxquels ils ont \u00e9t\u00e9 confront\u00e9s en ce qui concerne la pand\u00e9mie et de la fa\u00e7on dont leur institution financi\u00e8re les a aid\u00e9s \u00e0 traverser la temp\u00eate.<\/p>\n\n\n\n<p>L\u2019\u00e9pisode de cette semaine met en vedette Nicolas Wegel, fondateur de l\u2019entreprise de construction <a href=\"http:\/\/eac-construction.com\/\">montr\u00e9alaise EAC Construction<\/a>.<\/p>\n\n\n\n<p>\u00c9coutez le point de vue de Nicolas sur le fait d\u2019\u00eatre dans une industrie qui n\u2019est pas traditionnellement connue pour \u00eatre inclusive, et les d\u00e9fis uniques auxquels les entreprises de construction sont confront\u00e9es compte tenu des restrictions COVID-19.<\/p>\n\n\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Octobre est le Mois de la PME, et en collaboration avec la TD, nous dressons le profil des petites entreprises appartenant \u00e0 des personnes 2ELGBTQI+ partout au Canada qui ont r\u00e9ussi \u00e0 traverser la pand\u00e9mie de COVID-19. Nous discuterons de la fa\u00e7on dont ils ont r\u00e9ussi, de certains des d\u00e9fis auxquels ils ont \u00e9t\u00e9 confront\u00e9s en ce qui concerne la pand\u00e9mie et de la fa\u00e7on dont leur institution financi\u00e8re les a aid\u00e9s \u00e0 traverser la temp\u00eate. L\u2019\u00e9pisode de cette semaine met en vedette Nicolas Wegel, fondateur de l\u2019entreprise de construction montr\u00e9alaise EAC Construction. \u00c9coutez le point de vue de Nicolas sur le fait d\u2019\u00eatre dans une industrie qui n\u2019est pas traditionnellement connue pour \u00eatre inclusive, et les d\u00e9fis uniques auxquels les entreprises de construction sont confront\u00e9es compte tenu des restrictions COVID-19.<\/p>\n","protected":false},"author":1,"featured_media":60885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_trash_the_other_posts":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","editor_notices":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-60883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"jetpack_featured_media_url":"https:\/\/queerchamber.ca\/fr\/wp-content\/uploads\/sites\/7\/2025\/10\/eac-social.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/posts\/60883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/comments?post=60883"}],"version-history":[{"count":1,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/posts\/60883\/revisions"}],"predecessor-version":[{"id":60884,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/posts\/60883\/revisions\/60884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/media\/60885"}],"wp:attachment":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/media?parent=60883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/categories?post=60883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tags?post=60883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}