{"id":45497,"date":"2024-05-01T14:25:15","date_gmt":"2024-05-01T21:25:15","guid":{"rendered":"https:\/\/dev-cglcc-multisite.pantheonsite.io\/fr\/cglcc\/event\/explorer-la-diversite-et-linclusion-des-personnes-2slgbtqi-dans-lindustrie-touristique-zoom-2\/"},"modified":"2024-05-01T14:40:31","modified_gmt":"2024-05-01T21:40:31","slug":"explorer-la-diversite-et-linclusion-des-personnes-2slgbtqi-dans-lindustrie-touristique-zoom-2","status":"publish","type":"tribe_events","link":"https:\/\/queerchamber.ca\/fr\/event\/explorer-la-diversite-et-linclusion-des-personnes-2slgbtqi-dans-lindustrie-touristique-zoom-2\/","title":{"rendered":"Explorer la diversit\u00e9 et l\u2019inclusion des personnes 2SLGBTQI+ dans l\u2019industrie touristique (Zoom)"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>Le march\u00e9 mondial des voyages 2SLGBTQI+ est \u00e9valu\u00e9 \u00e0 plus de 200 milliards de dollars par an. Les destinations canadiennes sont bien plac\u00e9es pour accro\u00eetre leur part de ce march\u00e9. Mais pour r\u00e9ussir, les destinations et les op\u00e9rateurs doivent veiller \u00e0 ce que les clients 2SLGBTQI+ se sentent les bienvenus, accept\u00e9s et soient servis d\u2019une mani\u00e8re qui d\u00e9passe leurs attentes et r\u00e9pond \u00e0 leurs besoins.<\/p>\n\n\n\n<p>Gr\u00e2ce au financement de ce projet, L\u2019Agence de promotion \u00e9conomique du Canada atlantique (APECA) s\u2019engage \u00e0 aider l\u2019industrie touristique du Canada atlantique \u00e0 devenir accueillante pour les personnes 2SLGBTQI+ et \u00e0 promouvoir les destinations et les produits touristiques du Canada atlantique aupr\u00e8s du march\u00e9 des voyages 2SLGBTQI+ \u00e0 l\u2019\u00e9chelle internationale.<\/p>\n\n\n\n<p>Pour soutenir ces efforts de d\u00e9veloppement de produits pr\u00eats pour le march\u00e9, l\u2019atelier Explorer la diversit\u00e9 et l\u2019inclusion des personnes 2SLGBTQI+ dans l\u2019industrie touristique de CCQC aide les entreprises touristiques \u00e0 d\u00e9couvrir l\u2019inclusion 2SLGBTQI+, et \u00e0 comprendre, valoriser et servir efficacement les clients et les employ\u00e9s 2SLGBTQI+.<\/p>\n\n\n\n<p>Cette formation est pr\u00e9sent\u00e9e en format s\u00e9minaire en ligne (en direct via Zoom).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le march\u00e9 mondial des voyages 2SLGBTQI+ est \u00e9valu\u00e9 \u00e0 plus de 200 milliards de dollars par an. Les destinations canadiennes sont bien plac\u00e9es pour accro\u00eetre leur part de ce march\u00e9. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"single-event-custom","meta":{"_acf_changed":false,"_tec_requires_first_save":false,"_trash_the_other_posts":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_EventAllDay":false,"_EventTimezone":"America\/Vancouver","_EventStartDate":"2023-03-29 14:00:00","_EventEndDate":"2023-03-29 17:00:00","_EventStartDateUTC":"2023-03-29 21:00:00","_EventEndDateUTC":"2023-03-30 00:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"https:\/\/us06web.zoom.us\/meeting\/register\/tZctf-uhrzkrHt2NbXCChslKVIi3Iy72AfPf","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","editor_notices":[],"_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[242,248],"class_list":["post-45497","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-national","tribe_events_cat-rainbow-registered","cat_national","cat_rainbow-registered"],"acf":[],"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/45497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/45497\/revisions"}],"wp:attachment":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/media?parent=45497"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tags?post=45497"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=45497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}