{"id":45577,"date":"2024-05-01T14:27:03","date_gmt":"2024-05-01T21:27:03","guid":{"rendered":"https:\/\/dev-cglcc-multisite.pantheonsite.io\/fr\/cglcc\/event\/rainbow-registered-holiday-gift-guide\/"},"modified":"2024-12-02T11:33:32","modified_gmt":"2024-12-02T16:33:32","slug":"rainbow-registered-holiday-gift-guide","status":"publish","type":"tribe_events","link":"https:\/\/queerchamber.ca\/fr\/event\/rainbow-registered-holiday-gift-guide\/","title":{"rendered":"Rainbow Registered Holiday Gift Guide 2023"},"content":{"rendered":"\n<p>Dive into a world of unique, inclusive gifts from Rainbow Registered accredited businesses. Support 2S2SLGBTQI+ friendly businesses this festive season. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dive into a world of unique, inclusive gifts from Rainbow Registered accredited businesses. Support 2S2SLGBTQI+ friendly businesses this festive season.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"single-event-custom","meta":{"_acf_changed":false,"_tec_requires_first_save":false,"_trash_the_other_posts":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_EventAllDay":false,"_EventTimezone":"America\/Vancouver","_EventStartDate":"2023-11-01 00:00:00","_EventEndDate":"2023-12-31 23:59:00","_EventStartDateUTC":"2023-11-01 07:00:00","_EventEndDateUTC":"2024-01-01 07:59:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"https:\/\/www.rainbowregisteredstore.ca\/","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","editor_notices":[],"_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[246,245,242,243,244,247,248],"class_list":["post-45577","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-supplier","tribe_events_cat-corporate","tribe_events_cat-national","tribe_events_cat-national-non-voting","tribe_events_cat-national-voting","tribe_events_cat-out-for-business","tribe_events_cat-rainbow-registered","cat_supplier","cat_corporate","cat_national","cat_national-non-voting","cat_national-voting","cat_out-for-business","cat_rainbow-registered"],"acf":[],"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/45577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/45577\/revisions"}],"wp:attachment":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/media?parent=45577"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tags?post=45577"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=45577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}