{"id":45588,"date":"2024-05-01T14:27:13","date_gmt":"2024-05-01T21:27:13","guid":{"rendered":"https:\/\/dev-cglcc-multisite.pantheonsite.io\/fr\/cglcc\/event\/whats-the-buzz-connect-and-learn-with-rainbow-registered-february-2024\/"},"modified":"2024-06-18T18:29:22","modified_gmt":"2024-06-18T22:29:22","slug":"whats-the-buzz-feb-27-2024","status":"publish","type":"tribe_events","link":"https:\/\/queerchamber.ca\/fr\/event\/whats-the-buzz-feb-27-2024\/","title":{"rendered":"What\u2019s the Buzz? Connect and learn with Rainbow Registered (February 2024)"},"content":{"rendered":"\n<p>Dates: February 27, 2024 12:00 pm &#8211; February 27, 2024 1:00 pm ET<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>PLEASE NOTE: This event is open to businesses that are presently accredited in <a href=\"https:\/\/queerchamber.ca\/fr\/cglcc\/programs\/rainbow-registered\/\" data-type=\"URL\" data-id=\"https:\/\/queerchamber.ca\/fr\/cglcc\/programs\/rainbow-registered\/\" target=\"_blank\" rel=\"noreferrer noopener\">the Rainbow Registered program<\/a> or those who have submitted their program application. Join us for the latest updates on all of our activities, opportunities for education, networking and best practice sharing.\u00a0\u00a0<\/p>\n\n\n\n<p><strong>Important: Registration link for this session will be sent to all eligible businesses via e-mail in advance.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dates: February 27, 2024 12:00 pm &#8211; February 27, 2024 1:00 pm ET PLEASE NOTE: This event is open to businesses that are presently accredited in the Rainbow Registered program [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"single-event-custom","meta":{"_acf_changed":false,"_tec_requires_first_save":false,"_trash_the_other_posts":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_EventAllDay":false,"_EventTimezone":"America\/Vancouver","_EventStartDate":"2024-02-27 12:00:00","_EventEndDate":"2024-02-27 13:00:00","_EventStartDateUTC":"2024-02-27 20:00:00","_EventEndDateUTC":"2024-02-27 21:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","editor_notices":[],"_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[248],"class_list":["post-45588","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-rainbow-registered","cat_rainbow-registered"],"acf":[],"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/45588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/45588\/revisions"}],"wp:attachment":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/media?parent=45588"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tags?post=45588"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=45588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}