{"id":47352,"date":"2024-07-11T16:01:31","date_gmt":"2024-07-11T20:01:31","guid":{"rendered":"https:\/\/dev-cglcc-multisite.pantheonsite.io\/fr\/cglcc\/event\/defier-2024\/"},"modified":"2024-07-11T16:01:31","modified_gmt":"2024-07-11T20:01:31","slug":"defier-2024","status":"publish","type":"tribe_events","link":"https:\/\/queerchamber.ca\/fr\/event\/defier-2024\/","title":{"rendered":"D\u00c9FIER 2024"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">L&#8217;\u00e9v\u00e9nement le plus important au Canada d\u00e9di\u00e9 \u00e0 la Diversit\u00e9 des fournisseurs<\/h2>\n\n\n\n<p>Cette ann\u00e9e, CAMSC, CCQC et IWSCC (SDAC), en collaboration avec WEConnect International en tant que partenaire de l&#8217;\u00e9v\u00e9nement, unissent leurs forces pour vous offrir une exp\u00e9rience in\u00e9gal\u00e9e en mati\u00e8re de diversit\u00e9 des fournisseurs. Nous avons combin\u00e9 nos programmes pour fa\u00e7onner l&#8217;avenir de la diversit\u00e9 des fournisseurs au Canada et au-del\u00e0. Notre conf\u00e9rence de trois jours accueille des centaines de fournisseurs et d&#8217;entreprises provenant de quatre r\u00e9seaux dynamiques, vous offrant des opportunit\u00e9s in\u00e9dites d&#8217;apprentissage, de connexion et de croissance.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">DEFY 2024: \u00e0 quoi vous attendre?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Discours d&#8217;ouverture inspirants : \u00c9coutez les leaders de l&#8217;industrie et obtenez des id\u00e9es qui fa\u00e7onneront votre croissance de mani\u00e8re significative.<\/li>\n\n\n\n<li>Opportunit\u00e9s de r\u00e9seautage diverses : Tissez des liens avec des entrepreneur.e.s et des dirigeant.e.s d&#8217;entreprise partageant les m\u00eames id\u00e9es, et ouvrez la porte \u00e0 de pr\u00e9cieux partenariats.<\/li>\n\n\n\n<li>Ateliers interactifs : Aiguisez vos comp\u00e9tences et restez en avance sur la courbe avec des sessions de travail captivantes. Approfondissez des sujets tels que l&#8217;IA, la diversit\u00e9, l&#8217;\u00e9quit\u00e9 et l&#8217;inclusion, et la durabilit\u00e9 pour faire progresser vos connaissances au niveau sup\u00e9rieur.<\/li>\n\n\n\n<li>Salon professionnel : Mettez en valeur votre entreprise et nouez des partenariats avec de nouveaux partenaires gr\u00e2ce \u00e0 un salon professionnel dynamique pr\u00e9sentant des sponsors, des entreprises et des fournisseurs de tous les secteurs et de tous les niveaux.<\/li>\n\n\n\n<li>Sessions de mise en relation exclusives : Con\u00e7ues sp\u00e9cifiquement pour les fournisseurs certifi\u00e9s et les partenaires d&#8217;entreprise, ces sessions ouvrent la porte \u00e0 des collaborations strat\u00e9giques dans tout le r\u00e9seau SDAC.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Fa\u00e7onner l&#8217;avenir \u00e0 DEFY\/D\u00c9FIER 2024 <\/h2>\n\n\n\n<p>Alors que nous naviguons dans des r\u00e9alit\u00e9s complexes \u00e0 la fois sur le plan politique et \u00e9conomique, nous nous demandons souvent comment d\u00e9fier les probabilit\u00e9s. Comment remettre en question la tradition et encourager de nouvelles solutions innovantes ? Comment orienter nos entreprises dans la bonne direction ? En fin de compte, comment soutenir et faciliter la croissance et l&#8217;expansion de nos entreprises au-del\u00e0 des fronti\u00e8res ?<\/p>\n\n\n\n<p>Depuis ces derni\u00e8res ann\u00e9es, nous soutenons qu&#8217;une cha\u00eene d&#8217;approvisionnement diversifi\u00e9e est une cha\u00eene d&#8217;approvisionnement r\u00e9siliente. La flexibilit\u00e9 pour s&#8217;adapter est cruciale lorsque l&#8217;environnement est en constante \u00e9volution.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.supplierdiversityalliance.ca\/defy-conference-2024\">Infos et inscription<\/a><\/div>\n<\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9v\u00e9nement le plus important au Canada d\u00e9di\u00e9 \u00e0 la Diversit\u00e9 des fournisseurs Cette ann\u00e9e, CAMSC, CCQC et IWSCC (SDAC), en collaboration avec WEConnect International en tant que partenaire de l&#8217;\u00e9v\u00e9nement, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":false,"_trash_the_other_posts":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_EventAllDay":false,"_EventTimezone":"America\/Toronto","_EventStartDate":"2024-06-12 07:00:00","_EventEndDate":"2024-06-12 07:00:00","_EventStartDateUTC":"2024-06-12 11:00:00","_EventEndDateUTC":"2024-06-12 11:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","editor_notices":[],"_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[],"class_list":["post-47352","tribe_events","type-tribe_events","status-publish","hentry"],"acf":[],"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/47352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events\/47352\/revisions"}],"wp:attachment":[{"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/media?parent=47352"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tags?post=47352"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/queerchamber.ca\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=47352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}